{"id":4474,"date":"2020-08-31T09:04:19","date_gmt":"2020-08-31T07:04:19","guid":{"rendered":"https:\/\/www.gima-ziegel.de\/?post_type=referenzen&#038;p=4474"},"modified":"2022-02-07T08:55:57","modified_gmt":"2022-02-07T07:55:57","slug":"fraunhofer-institut-fuer-igcv","status":"publish","type":"referenzen","link":"https:\/\/www.gima-ziegel.de\/de\/referenzen\/fraunhofer-institut-fuer-igcv\/","title":{"rendered":"Fraunhofer-Institut f\u00fcr IGCV"},"featured_media":4492,"template":"","produktart":[62,65],"farbe":[92],"produktkategorie":[27],"bauvorhaben":[53],"class_list":["post-4474","referenzen","type-referenzen","status-publish","has-post-thumbnail","hentry","produktart-klinker-nf-df","produktart-klinkerfertigteile","farbe-schwarz","produktkategorie-klinker-fassade","bauvorhaben-oeffentliches-gebaeude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GIMA - Qualit\u00e4t aus Ton - Fraunhofer-Institut f\u00fcr IGCV<\/title>\n<meta name=\"description\" content=\"Hier finden Sie umfassende Informationen zu unserer Referenz Fraunhofer-Institut f\u00fcr IGCV. \u00dcberzeugen Sie sich von unserer Qualit\u00e4t.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gima-ziegel.de\/de\/referenzen\/fraunhofer-institut-fuer-igcv\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GIMA - Qualit\u00e4t aus Ton - Fraunhofer-Institut f\u00fcr IGCV\" \/>\n<meta property=\"og:description\" content=\"Hier finden Sie umfassende Informationen zu unserer Referenz Fraunhofer-Institut f\u00fcr IGCV. \u00dcberzeugen Sie sich von unserer Qualit\u00e4t.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gima-ziegel.de\/de\/referenzen\/fraunhofer-institut-fuer-igcv\/\" \/>\n<meta property=\"og:site_name\" content=\"Gima\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-07T07:55:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gima-ziegel.de\/wp-content\/uploads\/Augsburg-IGCV-2020-011_Burkhardt-Walther.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gima-ziegel.de\\\/de\\\/referenzen\\\/fraunhofer-institut-fuer-igcv\\\/\",\"url\":\"https:\\\/\\\/www.gima-ziegel.de\\\/de\\\/referenzen\\\/fraunhofer-institut-fuer-igcv\\\/\",\"name\":\"GIMA - Qualit\u00e4t aus Ton - Fraunhofer-Institut f\u00fcr IGCV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gima-ziegel.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.gima-ziegel.de\\\/de\\\/referenzen\\\/fraunhofer-institut-fuer-igcv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gima-ziegel.de\\\/de\\\/referenzen\\\/fraunhofer-institut-fuer-igcv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gima-ziegel.de\\\/wp-content\\\/uploads\\\/Augsburg-IGCV-2020-011_Burkhardt-Walther.jpg\",\"datePublished\":\"2020-08-31T07:04:19+00:00\",\"dateModified\":\"2022-02-07T07:55:57+00:00\",\"description\":\"Hier finden Sie umfassende Informationen zu unserer Referenz Fraunhofer-Institut f\u00fcr IGCV. \u00dcberzeugen Sie sich von unserer Qualit\u00e4t.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gima-ziegel.de\\\/de\\\/referenzen\\\/fraunhofer-institut-fuer-igcv\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gima-ziegel.de\\\/de\\\/referenzen\\\/fraunhofer-institut-fuer-igcv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.gima-ziegel.de\\\/de\\\/referenzen\\\/fraunhofer-institut-fuer-igcv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.gima-ziegel.de\\\/wp-content\\\/uploads\\\/Augsburg-IGCV-2020-011_Burkhardt-Walther.jpg\",\"contentUrl\":\"https:\\\/\\\/www.gima-ziegel.de\\\/wp-content\\\/uploads\\\/Augsburg-IGCV-2020-011_Burkhardt-Walther.jpg\",\"width\":1300,\"height\":701,\"caption\":\"Burkhard Walther | Henning Larsen Architects, M\u00fcnchen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gima-ziegel.de\\\/de\\\/referenzen\\\/fraunhofer-institut-fuer-igcv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.gima-ziegel.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fraunhofer-Institut f\u00fcr IGCV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gima-ziegel.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.gima-ziegel.de\\\/en\\\/\",\"name\":\"Gima\",\"description\":\"Qualit\u00e4t aus Ton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gima-ziegel.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GIMA - Qualit\u00e4t aus Ton - Fraunhofer-Institut f\u00fcr IGCV","description":"Hier finden Sie umfassende Informationen zu unserer Referenz Fraunhofer-Institut f\u00fcr IGCV. \u00dcberzeugen Sie sich von unserer Qualit\u00e4t.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gima-ziegel.de\/de\/referenzen\/fraunhofer-institut-fuer-igcv\/","og_locale":"de_DE","og_type":"article","og_title":"GIMA - Qualit\u00e4t aus Ton - Fraunhofer-Institut f\u00fcr IGCV","og_description":"Hier finden Sie umfassende Informationen zu unserer Referenz Fraunhofer-Institut f\u00fcr IGCV. \u00dcberzeugen Sie sich von unserer Qualit\u00e4t.","og_url":"https:\/\/www.gima-ziegel.de\/de\/referenzen\/fraunhofer-institut-fuer-igcv\/","og_site_name":"Gima","article_modified_time":"2022-02-07T07:55:57+00:00","og_image":[{"width":1300,"height":701,"url":"https:\/\/www.gima-ziegel.de\/wp-content\/uploads\/Augsburg-IGCV-2020-011_Burkhardt-Walther.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.gima-ziegel.de\/de\/referenzen\/fraunhofer-institut-fuer-igcv\/","url":"https:\/\/www.gima-ziegel.de\/de\/referenzen\/fraunhofer-institut-fuer-igcv\/","name":"GIMA - Qualit\u00e4t aus Ton - Fraunhofer-Institut f\u00fcr IGCV","isPartOf":{"@id":"https:\/\/www.gima-ziegel.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gima-ziegel.de\/de\/referenzen\/fraunhofer-institut-fuer-igcv\/#primaryimage"},"image":{"@id":"https:\/\/www.gima-ziegel.de\/de\/referenzen\/fraunhofer-institut-fuer-igcv\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gima-ziegel.de\/wp-content\/uploads\/Augsburg-IGCV-2020-011_Burkhardt-Walther.jpg","datePublished":"2020-08-31T07:04:19+00:00","dateModified":"2022-02-07T07:55:57+00:00","description":"Hier finden Sie umfassende Informationen zu unserer Referenz Fraunhofer-Institut f\u00fcr IGCV. \u00dcberzeugen Sie sich von unserer Qualit\u00e4t.","breadcrumb":{"@id":"https:\/\/www.gima-ziegel.de\/de\/referenzen\/fraunhofer-institut-fuer-igcv\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gima-ziegel.de\/de\/referenzen\/fraunhofer-institut-fuer-igcv\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.gima-ziegel.de\/de\/referenzen\/fraunhofer-institut-fuer-igcv\/#primaryimage","url":"https:\/\/www.gima-ziegel.de\/wp-content\/uploads\/Augsburg-IGCV-2020-011_Burkhardt-Walther.jpg","contentUrl":"https:\/\/www.gima-ziegel.de\/wp-content\/uploads\/Augsburg-IGCV-2020-011_Burkhardt-Walther.jpg","width":1300,"height":701,"caption":"Burkhard Walther | Henning Larsen Architects, M\u00fcnchen"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gima-ziegel.de\/de\/referenzen\/fraunhofer-institut-fuer-igcv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.gima-ziegel.de\/de\/"},{"@type":"ListItem","position":2,"name":"Fraunhofer-Institut f\u00fcr IGCV"}]},{"@type":"WebSite","@id":"https:\/\/www.gima-ziegel.de\/en\/#website","url":"https:\/\/www.gima-ziegel.de\/en\/","name":"Gima","description":"Qualit\u00e4t aus Ton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gima-ziegel.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.gima-ziegel.de\/de\/wp-json\/wp\/v2\/referenzen\/4474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gima-ziegel.de\/de\/wp-json\/wp\/v2\/referenzen"}],"about":[{"href":"https:\/\/www.gima-ziegel.de\/de\/wp-json\/wp\/v2\/types\/referenzen"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gima-ziegel.de\/de\/wp-json\/wp\/v2\/media\/4492"}],"wp:attachment":[{"href":"https:\/\/www.gima-ziegel.de\/de\/wp-json\/wp\/v2\/media?parent=4474"}],"wp:term":[{"taxonomy":"produktart","embeddable":true,"href":"https:\/\/www.gima-ziegel.de\/de\/wp-json\/wp\/v2\/produktart?post=4474"},{"taxonomy":"farbe","embeddable":true,"href":"https:\/\/www.gima-ziegel.de\/de\/wp-json\/wp\/v2\/farbe?post=4474"},{"taxonomy":"produktkategorie","embeddable":true,"href":"https:\/\/www.gima-ziegel.de\/de\/wp-json\/wp\/v2\/produktkategorie?post=4474"},{"taxonomy":"bauvorhaben","embeddable":true,"href":"https:\/\/www.gima-ziegel.de\/de\/wp-json\/wp\/v2\/bauvorhaben?post=4474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}