{"id":9694,"date":"2022-02-14T11:00:15","date_gmt":"2022-02-14T10:00:15","guid":{"rendered":"https:\/\/www.gima-ziegel.de\/?post_type=referenzen&#038;p=9694"},"modified":"2022-02-14T11:05:38","modified_gmt":"2022-02-14T10:05:38","slug":"geistlich-areal","status":"publish","type":"referenzen","link":"https:\/\/www.gima-ziegel.de\/de\/referenzen\/geistlich-areal\/","title":{"rendered":"Geistlich Areal"},"featured_media":9696,"template":"","produktart":[95],"farbe":[34],"produktkategorie":[28],"bauvorhaben":[53],"class_list":["post-9694","referenzen","type-referenzen","status-publish","has-post-thumbnail","hentry","produktart-ziegelbodenplatten","farbe-rot","produktkategorie-pflaster-boden","bauvorhaben-oeffentliches-gebaeude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GIMA - Qualit\u00e4t aus Ton - Geistlich Areal<\/title>\n<meta name=\"description\" content=\"Hier finden Sie umfassende Informationen zu unserer Referenz Geistlich Areal. \u00dcberzeugen Sie sich von unserer Qualit\u00e4t.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gima-ziegel.de\/de\/referenzen\/geistlich-areal\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GIMA - Qualit\u00e4t aus Ton - Geistlich Areal\" \/>\n<meta property=\"og:description\" content=\"Hier finden Sie umfassende Informationen zu unserer Referenz Geistlich Areal. \u00dcberzeugen Sie sich von unserer Qualit\u00e4t.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gima-ziegel.de\/de\/referenzen\/geistlich-areal\/\" \/>\n<meta property=\"og:site_name\" content=\"Gima\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-14T10:05:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gima-ziegel.de\/wp-content\/uploads\/CH_Schlieren_Geistlich-Areal-01_Fehlmann-AG.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gima-ziegel.de\\\/de\\\/referenzen\\\/geistlich-areal\\\/\",\"url\":\"https:\\\/\\\/www.gima-ziegel.de\\\/de\\\/referenzen\\\/geistlich-areal\\\/\",\"name\":\"GIMA - Qualit\u00e4t aus Ton - Geistlich Areal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gima-ziegel.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.gima-ziegel.de\\\/de\\\/referenzen\\\/geistlich-areal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gima-ziegel.de\\\/de\\\/referenzen\\\/geistlich-areal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gima-ziegel.de\\\/wp-content\\\/uploads\\\/CH_Schlieren_Geistlich-Areal-01_Fehlmann-AG.jpg\",\"datePublished\":\"2022-02-14T10:00:15+00:00\",\"dateModified\":\"2022-02-14T10:05:38+00:00\",\"description\":\"Hier finden Sie umfassende Informationen zu unserer Referenz Geistlich Areal. \u00dcberzeugen Sie sich von unserer Qualit\u00e4t.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gima-ziegel.de\\\/de\\\/referenzen\\\/geistlich-areal\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gima-ziegel.de\\\/de\\\/referenzen\\\/geistlich-areal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.gima-ziegel.de\\\/de\\\/referenzen\\\/geistlich-areal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.gima-ziegel.de\\\/wp-content\\\/uploads\\\/CH_Schlieren_Geistlich-Areal-01_Fehlmann-AG.jpg\",\"contentUrl\":\"https:\\\/\\\/www.gima-ziegel.de\\\/wp-content\\\/uploads\\\/CH_Schlieren_Geistlich-Areal-01_Fehlmann-AG.jpg\",\"width\":1300,\"height\":700,\"caption\":\"Fehlmann AG | Graber Pulver Architekten, Z\u00fcrich\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gima-ziegel.de\\\/de\\\/referenzen\\\/geistlich-areal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.gima-ziegel.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Geistlich Areal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gima-ziegel.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.gima-ziegel.de\\\/en\\\/\",\"name\":\"Gima\",\"description\":\"Qualit\u00e4t aus Ton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gima-ziegel.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GIMA - Qualit\u00e4t aus Ton - Geistlich Areal","description":"Hier finden Sie umfassende Informationen zu unserer Referenz Geistlich Areal. \u00dcberzeugen Sie sich von unserer Qualit\u00e4t.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gima-ziegel.de\/de\/referenzen\/geistlich-areal\/","og_locale":"de_DE","og_type":"article","og_title":"GIMA - Qualit\u00e4t aus Ton - Geistlich Areal","og_description":"Hier finden Sie umfassende Informationen zu unserer Referenz Geistlich Areal. \u00dcberzeugen Sie sich von unserer Qualit\u00e4t.","og_url":"https:\/\/www.gima-ziegel.de\/de\/referenzen\/geistlich-areal\/","og_site_name":"Gima","article_modified_time":"2022-02-14T10:05:38+00:00","og_image":[{"width":1300,"height":700,"url":"https:\/\/www.gima-ziegel.de\/wp-content\/uploads\/CH_Schlieren_Geistlich-Areal-01_Fehlmann-AG.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.gima-ziegel.de\/de\/referenzen\/geistlich-areal\/","url":"https:\/\/www.gima-ziegel.de\/de\/referenzen\/geistlich-areal\/","name":"GIMA - Qualit\u00e4t aus Ton - Geistlich Areal","isPartOf":{"@id":"https:\/\/www.gima-ziegel.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gima-ziegel.de\/de\/referenzen\/geistlich-areal\/#primaryimage"},"image":{"@id":"https:\/\/www.gima-ziegel.de\/de\/referenzen\/geistlich-areal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gima-ziegel.de\/wp-content\/uploads\/CH_Schlieren_Geistlich-Areal-01_Fehlmann-AG.jpg","datePublished":"2022-02-14T10:00:15+00:00","dateModified":"2022-02-14T10:05:38+00:00","description":"Hier finden Sie umfassende Informationen zu unserer Referenz Geistlich Areal. \u00dcberzeugen Sie sich von unserer Qualit\u00e4t.","breadcrumb":{"@id":"https:\/\/www.gima-ziegel.de\/de\/referenzen\/geistlich-areal\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gima-ziegel.de\/de\/referenzen\/geistlich-areal\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.gima-ziegel.de\/de\/referenzen\/geistlich-areal\/#primaryimage","url":"https:\/\/www.gima-ziegel.de\/wp-content\/uploads\/CH_Schlieren_Geistlich-Areal-01_Fehlmann-AG.jpg","contentUrl":"https:\/\/www.gima-ziegel.de\/wp-content\/uploads\/CH_Schlieren_Geistlich-Areal-01_Fehlmann-AG.jpg","width":1300,"height":700,"caption":"Fehlmann AG | Graber Pulver Architekten, Z\u00fcrich"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gima-ziegel.de\/de\/referenzen\/geistlich-areal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.gima-ziegel.de\/de\/"},{"@type":"ListItem","position":2,"name":"Geistlich Areal"}]},{"@type":"WebSite","@id":"https:\/\/www.gima-ziegel.de\/en\/#website","url":"https:\/\/www.gima-ziegel.de\/en\/","name":"Gima","description":"Qualit\u00e4t aus Ton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gima-ziegel.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.gima-ziegel.de\/de\/wp-json\/wp\/v2\/referenzen\/9694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gima-ziegel.de\/de\/wp-json\/wp\/v2\/referenzen"}],"about":[{"href":"https:\/\/www.gima-ziegel.de\/de\/wp-json\/wp\/v2\/types\/referenzen"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gima-ziegel.de\/de\/wp-json\/wp\/v2\/media\/9696"}],"wp:attachment":[{"href":"https:\/\/www.gima-ziegel.de\/de\/wp-json\/wp\/v2\/media?parent=9694"}],"wp:term":[{"taxonomy":"produktart","embeddable":true,"href":"https:\/\/www.gima-ziegel.de\/de\/wp-json\/wp\/v2\/produktart?post=9694"},{"taxonomy":"farbe","embeddable":true,"href":"https:\/\/www.gima-ziegel.de\/de\/wp-json\/wp\/v2\/farbe?post=9694"},{"taxonomy":"produktkategorie","embeddable":true,"href":"https:\/\/www.gima-ziegel.de\/de\/wp-json\/wp\/v2\/produktkategorie?post=9694"},{"taxonomy":"bauvorhaben","embeddable":true,"href":"https:\/\/www.gima-ziegel.de\/de\/wp-json\/wp\/v2\/bauvorhaben?post=9694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}